{"id":630,"date":"2024-09-24T18:15:44","date_gmt":"2024-09-24T16:15:44","guid":{"rendered":"https:\/\/www.vinhoselection.com\/blog\/?p=630"},"modified":"2024-11-12T21:14:16","modified_gmt":"2024-11-12T20:14:16","slug":"le-vignoble-de-georgie-une-viticulture-millenaire","status":"publish","type":"post","link":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/","title":{"rendered":"Le vignoble de G\u00e9orgie, une viticulture mill\u00e9naire"},"content":{"rendered":"\n<p><strong>Avec plus de 8000 ans d\u2019histoire, le vignoble g\u00e9orgien fait partie des plus anciens au monde. Ce berceau de la viticulture incarne aujourd\u2019hui la rencontre d\u2019un savoir-faire ancestral et de pratiques modernes. Des c\u00e9l\u00e8bres qvevris aux vins qu\u2019il propose, partez \u00e0 sa d\u00e9couverte&nbsp;!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La tradition des qvevris<\/h2>\n\n\n\n<p>C\u2019est gr\u00e2ce \u00e0 des fouilles arch\u00e9ologiques que l\u2019on a pu d\u00e9celer son existence lors de la p\u00e9riode n\u00e9olithique. Dans ces trouvailles, des p\u00e9pins de raisin et des vestiges de poteries que l\u2019on utilisait alors pour la fermentation du vin. En effet, ils avaient d\u00e9velopp\u00e9 une m\u00e9thode sp\u00e9cifique qui a travers\u00e9 les \u00e2ges&nbsp;: la vinification en <a href=\"https:\/\/www.vinhoselection.com\/blog\/2024\/02\/20\/barriques-cuves-amphores-dans-quoi-fait-on-le-vin\/\">qvevris<\/a>, de grandes amphores en terre cuite enterr\u00e9es dans le sol. Elles engendrent une fermentation naturelle, commun\u00e9ment avec les peaux, les rafles, et parfois les p\u00e9pins, ainsi qu\u2019une maturation du pr\u00e9cieux nectar. Dans le verre, les rouges provenant de ce processus ont des tanins prononc\u00e9s et une palette complexe. Les blancs, souvent cat\u00e9goris\u00e9s comme ambr\u00e9s ou <a href=\"https:\/\/www.vinhoselection.com\/blog\/2023\/09\/11\/quest-ce-quun-vin-orange\/\">oranges<\/a>, ont une robe profonde et des senteurs de fruits secs, de miel et d\u2019\u00e9pices.<\/p>\n\n\n\n<p>Au fil du temps, la production viticole se perfectionne, se modernise et prosp\u00e8re, notamment au XIXe si\u00e8cle sous l\u2019Empire russe. Lorsque le pays obtient son ind\u00e9pendance en 1991, il op\u00e8re un retour aux techniques traditionnelles et d\u00e9cide de mettre en lumi\u00e8re les c\u00e9pages autochtones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une multiplicit\u00e9 de terroirs et c\u00e9pages<\/h2>\n\n\n\n<p>Si la G\u00e9orgie a r\u00e9ussi \u00e0 r\u00e9sister \u00e0 l\u2019\u00e9preuve du temps c\u2019est, entre autres qualit\u00e9s, gr\u00e2ce \u00e0 sa formidable diversit\u00e9 de terroirs. On peut citer quatre r\u00e9gions majeures ayant chacune ses particularit\u00e9s. La Kakh\u00e9tie, sans aucun doute la plus vaste et la plus r\u00e9put\u00e9e, est responsable de 70% des vins locaux. Ses terres d\u2019argiles, calcaires et sables baignent dans un climat continental id\u00e9al pour emmener les baies \u00e0 maturit\u00e9 optimale. L\u2019Im\u00e9r\u00e9thie, elle, est plus humide et riche en alluvions. Racha-Letchkhoumi est compos\u00e9e de reliefs montagneux \u00e0 l\u2019origine de vins doux issus de c\u00e9pages rares. Kartlie fait la part belle aux effervescents avec son environnement plus frais. Et Adjara, sur les rives de la mer Noire, profite de son influence subtropicale pour d\u00e9livrer des cuv\u00e9es empreintes de l\u00e9g\u00e8ret\u00e9.<\/p>\n\n\n\n<p>Mais qu\u2019en est-il de ces fameuses vari\u00e9t\u00e9s end\u00e9miques\u00a0? On en d\u00e9compte environ 500 diff\u00e9rentes, bien que certaines se d\u00e9marquent, aussi bien seules qu\u2019au c\u0153ur d\u2019assemblages. Saperavi, c\u00e9page rouge phare, donne des flacons riches et tanniques, \u00e0 la couleur profonde et connus pour leur potentiel de garde int\u00e9ressant. C\u00f4t\u00e9 blanc, le Rkatsiteli s\u2019impose \u00e0 travers des notes de fruits \u00e0 noyau, une acidit\u00e9 marqu\u00e9e et un superbe \u00e9quilibre. Et le Mtsvane offre fragrances florales et texture soyeuse.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"494\" src=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-2-1024x494.png\" alt=\"\" class=\"wp-image-632\" srcset=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-2-1024x494.png 1024w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-2-300x145.png 300w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-2-768x370.png 768w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-2.png 1437w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Vignoble de Tbilvino<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Tbilvino au service des coutumes g\u00e9orgiennes<\/h2>\n\n\n\n<p>D\u2019abord cr\u00e9\u00e9e en 1962 pour fournir une coop\u00e9rative viticole de l\u2019Union Sovi\u00e9tique, Tbilvino conna\u00eet un second souffle en 1999 lorsqu\u2019il s\u2019\u00e9tabli dans la Kakh\u00e9tie. Son objectif principal\u00a0? La qu\u00eate de la qualit\u00e9 en faisant briller \u00e0 nouveau la vinification g\u00e9orgienne. Petit \u00e0 petit elle apprend \u00e0 ma\u00eetriser les diverses techniques et r\u00e9nove ses \u00e9quipements afin d\u2019\u00eatre \u00e0 la hauteur de ses ambitions. Sur leurs 160 hectares de vignoble, les fr\u00e8res Zura et Girorgi Margvelashvili pr\u00f4nent une production associant traditions viticoles et technologies modernes. Ce n\u2019est donc pas un hasard si Vinho S\u00e9lection a choisi de leur faire confiance.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"492\" src=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-3-1024x492.png\" alt=\"\" class=\"wp-image-633\" srcset=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-3-1024x492.png 1024w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-3-300x144.png 300w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-3-768x369.png 768w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-3.png 1435w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Vignoble de Tbilvino<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.vinhoselection.com\/vin\/tbilivino-tsinandali-2022\/229\/\">Tbilivino Tsinandali 2022<\/a> r\u00e9uni le Rkatsiteli et le Mtsvane. Les baies sont r\u00e9colt\u00e9es manuellement avant d\u2019\u00eatre ferment\u00e9es en cuves inox. Le vin est ensuite b\u00e2tonn\u00e9 pour accentuer sa structure et son bouquet, et \u00e9lev\u00e9 en partie en barriques fran\u00e7aises. Rond et charmeur, il d\u00e9voile des parfums de raisin frais, de citron, de coing et de fleurs sauvages. Richesse, fra\u00eecheur et finale saline au rendez-vous lors de la d\u00e9gustation. <a href=\"https:\/\/www.vinhoselection.com\/vin\/tbilvino-mukuzani-2021\/228\/\">Tbilivino Mukuzani 2021<\/a>, monoc\u00e9page en Saperavi, opte pour une fermentation malolactique et un \u00e9levage partiel en f\u00fbts durant 2 \u00e0 3 mois. La cerise noire rencontre la prune et l\u2019amande dans un ensemble franc et juteux aux tanins d\u00e9licats. Enfin <a href=\"https:\/\/www.vinhoselection.com\/vin\/tbilvino-qvevris-2021\/230\/\">Tbilivino Qvevris 2021<\/a>, 100% Rkatsiteli, utilise des qvevris pour offrir une cuv\u00e9e rac\u00e9e oscillant entre notes de noix, miel, coing, poire et pin. Une attaque tannique, de jolis amers et une trame acide remarquable.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.vinhoselection.com\/vins\/&amp;c=GE\">D\u00e9couvrez nos vins de G\u00e9orgie<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec plus de 8000 ans d\u2019histoire, le vignoble g\u00e9orgien fait partie des plus anciens au monde. Ce berceau de la viticulture incarne aujourd\u2019hui la rencontre d\u2019un savoir-faire ancestral et de pratiques modernes. Des c\u00e9l\u00e8bres qvevris aux vins qu\u2019il propose, partez \u00e0 sa d\u00e9couverte\u00a0!<\/p>\n","protected":false},"author":1,"featured_media":631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,6],"tags":[72,87,152,73,88,154,9,10,153,70,71],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vins de G\u00e9orgie : c\u00e9pages et vins en qvevris, vins du monde<\/title>\n<meta name=\"description\" content=\"Explorez le vignoble mill\u00e9naire de G\u00e9orgie : c\u00e9pages autochtones, terroirs uniques et vinification en qvevris, vins du monde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vins de G\u00e9orgie : c\u00e9pages et vins en qvevris, vins du monde\" \/>\n<meta property=\"og:description\" content=\"Explorez le vignoble mill\u00e9naire de G\u00e9orgie : c\u00e9pages autochtones, terroirs uniques et vinification en qvevris, vins du monde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinho S\u00e9lection - Le Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T16:15:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T20:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1435\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Vinho S\u00e9lection\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vinho S\u00e9lection\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\"},\"author\":{\"name\":\"Vinho S\u00e9lection\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d\"},\"headline\":\"Le vignoble de G\u00e9orgie, une viticulture mill\u00e9naire\",\"datePublished\":\"2024-09-24T16:15:44+00:00\",\"dateModified\":\"2024-11-12T20:14:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\"},\"wordCount\":781,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#organization\"},\"keywords\":[\"distributeur vins du monde\",\"distributeur vins \u00e9trangers\",\"g\u00e9orgie\",\"importateur vins du monde\",\"importateur vins \u00e9trangers\",\"qvevri\",\"vin\",\"vin du monde\",\"vin g\u00e9orgien\",\"vins du monde\",\"vins \u00e9trangers\"],\"articleSection\":[\"Tous les articles\",\"Vignobles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\",\"name\":\"Vins de G\u00e9orgie : c\u00e9pages et vins en qvevris, vins du monde\",\"isPartOf\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#website\"},\"datePublished\":\"2024-09-24T16:15:44+00:00\",\"dateModified\":\"2024-11-12T20:14:16+00:00\",\"description\":\"Explorez le vignoble mill\u00e9naire de G\u00e9orgie : c\u00e9pages autochtones, terroirs uniques et vinification en qvevris, vins du monde.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.vinhoselection.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le vignoble de G\u00e9orgie, une viticulture mill\u00e9naire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#website\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/\",\"name\":\"Vinho S\u00e9lection - Le Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vinhoselection.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#organization\",\"name\":\"Vinho S\u00e9lection\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png\",\"contentUrl\":\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png\",\"width\":660,\"height\":86,\"caption\":\"Vinho S\u00e9lection\"},\"image\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d\",\"name\":\"Vinho S\u00e9lection\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g\",\"caption\":\"Vinho S\u00e9lection\"},\"sameAs\":[\"https:\/\/www.vinhoselection.com\/blog\"],\"url\":\"https:\/\/www.vinhoselection.com\/blog\/author\/18vinhoweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vins de G\u00e9orgie : c\u00e9pages et vins en qvevris, vins du monde","description":"Explorez le vignoble mill\u00e9naire de G\u00e9orgie : c\u00e9pages autochtones, terroirs uniques et vinification en qvevris, vins du monde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Vins de G\u00e9orgie : c\u00e9pages et vins en qvevris, vins du monde","og_description":"Explorez le vignoble mill\u00e9naire de G\u00e9orgie : c\u00e9pages autochtones, terroirs uniques et vinification en qvevris, vins du monde.","og_url":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/","og_site_name":"Vinho S\u00e9lection - Le Blog","article_published_time":"2024-09-24T16:15:44+00:00","article_modified_time":"2024-11-12T20:14:16+00:00","og_image":[{"width":1435,"height":687,"url":"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/09\/Tbilvino-1.png","type":"image\/png"}],"author":"Vinho S\u00e9lection","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Vinho S\u00e9lection","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#article","isPartOf":{"@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/"},"author":{"name":"Vinho S\u00e9lection","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d"},"headline":"Le vignoble de G\u00e9orgie, une viticulture mill\u00e9naire","datePublished":"2024-09-24T16:15:44+00:00","dateModified":"2024-11-12T20:14:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/"},"wordCount":781,"commentCount":0,"publisher":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#organization"},"keywords":["distributeur vins du monde","distributeur vins \u00e9trangers","g\u00e9orgie","importateur vins du monde","importateur vins \u00e9trangers","qvevri","vin","vin du monde","vin g\u00e9orgien","vins du monde","vins \u00e9trangers"],"articleSection":["Tous les articles","Vignobles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/","url":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/","name":"Vins de G\u00e9orgie : c\u00e9pages et vins en qvevris, vins du monde","isPartOf":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#website"},"datePublished":"2024-09-24T16:15:44+00:00","dateModified":"2024-11-12T20:14:16+00:00","description":"Explorez le vignoble mill\u00e9naire de G\u00e9orgie : c\u00e9pages autochtones, terroirs uniques et vinification en qvevris, vins du monde.","breadcrumb":{"@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/09\/24\/le-vignoble-de-georgie-une-viticulture-millenaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vinhoselection.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le vignoble de G\u00e9orgie, une viticulture mill\u00e9naire"}]},{"@type":"WebSite","@id":"https:\/\/www.vinhoselection.com\/blog\/#website","url":"https:\/\/www.vinhoselection.com\/blog\/","name":"Vinho S\u00e9lection - Le Blog","description":"","publisher":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vinhoselection.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vinhoselection.com\/blog\/#organization","name":"Vinho S\u00e9lection","url":"https:\/\/www.vinhoselection.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png","contentUrl":"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png","width":660,"height":86,"caption":"Vinho S\u00e9lection"},"image":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d","name":"Vinho S\u00e9lection","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g","caption":"Vinho S\u00e9lection"},"sameAs":["https:\/\/www.vinhoselection.com\/blog"],"url":"https:\/\/www.vinhoselection.com\/blog\/author\/18vinhoweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts\/630"}],"collection":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/comments?post=630"}],"version-history":[{"count":1,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts\/630\/revisions"}],"predecessor-version":[{"id":634,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts\/630\/revisions\/634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/media\/631"}],"wp:attachment":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/media?parent=630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/categories?post=630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/tags?post=630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}