{"id":535,"date":"2024-04-23T18:12:38","date_gmt":"2024-04-23T16:12:38","guid":{"rendered":"https:\/\/www.vinhoselection.com\/blog\/?p=535"},"modified":"2024-11-12T21:19:15","modified_gmt":"2024-11-12T20:19:15","slug":"le-vermentino-fraicheur-et-legerete-en-mediterranee","status":"publish","type":"post","link":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/","title":{"rendered":"Le Vermentino, fra\u00eecheur et l\u00e9g\u00e8ret\u00e9 en M\u00e9diterran\u00e9e"},"content":{"rendered":"\n<p><strong>Typ\u00e9 et aromatique, c\u2019est ainsi que l\u2019on pourrait d\u00e9finir simplement le Vermentino. Cette vari\u00e9t\u00e9 italienne, qui s\u2019\u00e9panouit de la Sardaigne \u00e0 la Hunter Valley, est \u00e0 l\u2019origine de vins blancs tendres aux profils \u00e9l\u00e9gants. Partez \u00e0 sa rencontre\u2026<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un c\u00e9page international<\/h2>\n\n\n\n<p>Difficile de d\u00e9finir avec pr\u00e9cision son berceau de naissance, tant les th\u00e9ories vont bon train. Quand certains le disent issu de Mad\u00e8re et d\u00e9velopp\u00e9 ensuite en Espagne, d\u2019autres r\u00e9pondent qu\u2019il vient de Gr\u00e8ce et se serait \u00e9tendu par le biais des marchands v\u00e9nitiens. Cependant, sa consonance r\u00e9solument italienne nous pousserait \u00e0 penser qu\u2019il viendrait de chez nos voisins transalpins, actuellement premier pays producteur de Vermentino &#8211; juste devant la France.<\/p>\n\n\n\n<p>Avec comme point de d\u00e9part l\u2019<a href=\"https:\/\/www.vinhoselection.com\/blog\/2023\/10\/05\/france-italie-une-mosaique-de-terroirs\/\">Italie<\/a>, donc, il a connu une belle expansion. D\u2019abord sur le littoral m\u00e9diterran\u00e9en en s\u2019implantant en Corse et en Provence , o\u00f9 on l\u2019appelle souvent Rolle, mais aussi en <a href=\"https:\/\/www.vinhoselection.com\/blog\/2023\/10\/12\/lespagne-vins-races-et-bodegas-a-perte-de-vue\/\">Espagne<\/a>, au Maroc et en Croatie. Il a ensuite parcouru du chemin, s\u2019enfon\u00e7ant un peu plus dans les terres europ\u00e9ennes pour toucher la Bulgarie, ou traversant la plan\u00e8te afin de se complaire au Chili et en <a href=\"https:\/\/www.vinhoselection.com\/blog\/2023\/09\/19\/a-la-decouverte-des-vignobles-daustralie\/\">Australie<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vignoble-1024x683.jpg\" alt=\"\" class=\"wp-image-539\" srcset=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vignoble-1024x683.jpg 1024w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vignoble-300x200.jpg 300w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vignoble-768x512.jpg 768w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vignoble.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">En qu\u00eate de terroirs gorg\u00e9s de soleil<\/h2>\n\n\n\n<p>Il est un c\u00e9page blanc incontournable des appellations corses, Patrimonio en t\u00eate. Un succ\u00e8s qui s\u2019explique par son app\u00e9tence pour le climat de l\u2019\u00eele de Beaut\u00e9. Car le Vermentino est vendang\u00e9 tardivement et n\u00e9cessite une m\u00e9t\u00e9o chaleureuse sans trop de pr\u00e9cipitations pour atteindre une maturit\u00e9 optimale, ainsi que d\u2019\u00eatre implant\u00e9 sur des terres avec une belle exposition. A l\u2019inverse, les climats froids et temp\u00e9r\u00e9s ralentissent sa maturation. Sur le pourtour m\u00e9diterran\u00e9en et dans le Nouveau Monde, il b\u00e9n\u00e9ficie d\u2019une situation climatique qui lui assure une superbe productivit\u00e9. S\u2019il est consid\u00e9r\u00e9 comme vigoureux, il est tout de m\u00eame sensible \u00e0 la pourriture acide et \u00e0 l\u2019o\u00efdium, et les vignerons pr\u00e9f\u00e8reront logiquement \u00e9viter les parcelles humides. Autre faiblesse, le vent. Pour y rem\u00e9dier, on le taille court avec une conduite sur fil de fer.<\/p>\n\n\n\n<p>Il serait un parent de la famille de c\u00e9pages malvoisie. Si vous avez la chance de parcourir les vignobles dans lesquels il est pr\u00e9sent, vous pourrez le reconna\u00eetre \u00e0 ses grandes grappes tronconiques. Ses feuilles, jaunes dans leur jeunesse, deviennent vert fonc\u00e9 avec l\u2019\u00e2ge. Et ses baies blanches adoptent une teinte ros\u00e9e lorsqu\u2019elles sont en surmaturit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vermentino-1024x683.jpeg\" alt=\"\" class=\"wp-image-537\" srcset=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vermentino-1024x683.jpeg 1024w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vermentino-300x200.jpeg 300w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vermentino-768x512.jpeg 768w, https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/vermentino.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Une explosion de saveurs<\/h2>\n\n\n\n<p>Il peut \u00eatre vinifi\u00e9 seul ou en assemblage. En monoc\u00e9page, il se distingue par sa l\u00e9g\u00e8ret\u00e9 et son gras. En compagnie d\u2019autres vari\u00e9t\u00e9s, parmi lesquelles le Cinsault, le Grenache, ou encore l\u2019Ugni Blanc, il apporte un c\u00f4t\u00e9 a\u00e9rien et une agr\u00e9able fra\u00eecheur. Il donne des vins blancs doux \u00e0 de rares occasions, et en grande majorit\u00e9 des blancs secs. Mais int\u00e9ressons-nous de plus pr\u00e8s \u00e0 la d\u00e9gustation de ces derniers.<\/p>\n\n\n\n<p>Sa robe p\u00e2le, d\u2019un jaune clair limpide, laisse place \u00e0 une palette aromatique \u00e0 la fois intense, fine et complexe. Les fragrances s\u2019encha\u00eenent et ne se ressemblent pas. On per\u00e7oit tour \u00e0 tour des notes florales type aub\u00e9pine ou tilleul, du fenouil, des agrumes comme le citron et le pamplemousse, des \u00e9pices douces et un floril\u00e8ge de fruits divers. La p\u00eache rencontre la poire, la pomme, l\u2019abricot, l\u2019ananas et l\u2019amande fra\u00eeche. Sans oublier de jolies notes iod\u00e9es et min\u00e9rales g\u00e9n\u00e9ralement apport\u00e9es par l\u2019influence marine dans laquelle baignent les vignes. Au palais, on remarque un vin tendre et suave, avec peu d\u2019acidit\u00e9. Les grands Vermentino poss\u00e8dent une texture raffin\u00e9e, une richesse aromatique sans pareille, et un bel \u00e9quilibre. En effet, ce c\u00e9page n\u2019est jamais lourd lorsqu\u2019il est travaill\u00e9 avec justesse. A savourer dans leur jeunesse, ils gagnent \u00e0 \u00eatre caraf\u00e9s lors du service pour d\u00e9livrer tout leur potentiel aromatique. Ils peuvent aussi attendre quelques ann\u00e9es en cave selon la mani\u00e8re dont ils ont \u00e9t\u00e9 vinifi\u00e9s.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.vinhoselection.com\/vins\/?region=&amp;appellation=&amp;domaine=&amp;cepage=Vermentino&amp;order=\">D\u00e9couvrez nos vins de Vermentino<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Typ\u00e9 et aromatique, c\u2019est ainsi que l\u2019on pourrait d\u00e9finir simplement le Vermentino. Cette vari\u00e9t\u00e9 italienne, qui s\u2019\u00e9panouit de la Sardaigne \u00e0 la Hunter Valley, est \u00e0 l\u2019origine de vins blancs tendres aux profils \u00e9l\u00e9gants. Partez \u00e0 sa rencontre\u2026<\/p>\n","protected":false},"author":1,"featured_media":536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,39],"tags":[17,72,87,73,88,121,9,10,60,70,71],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vermentino : fra\u00eecheur m\u00e9diterran\u00e9enne et subtil, vins du monde<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le Vermentino, c\u00e9page aromatique de M\u00e9diterran\u00e9e. Un vin blanc l\u00e9ger, \u00e9l\u00e9gant, aux notes d&#039;agrumes et de fleurs, vins du monde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vermentino : fra\u00eecheur m\u00e9diterran\u00e9enne et subtil, vins du monde\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le Vermentino, c\u00e9page aromatique de M\u00e9diterran\u00e9e. Un vin blanc l\u00e9ger, \u00e9l\u00e9gant, aux notes d&#039;agrumes et de fleurs, vins du monde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinho S\u00e9lection - Le Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T16:12:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T20:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/corse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vinho S\u00e9lection\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vinho S\u00e9lection\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\"},\"author\":{\"name\":\"Vinho S\u00e9lection\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d\"},\"headline\":\"Le Vermentino, fra\u00eecheur et l\u00e9g\u00e8ret\u00e9 en M\u00e9diterran\u00e9e\",\"datePublished\":\"2024-04-23T16:12:38+00:00\",\"dateModified\":\"2024-11-12T20:19:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\"},\"wordCount\":728,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#organization\"},\"keywords\":[\"d\u00e9gustation\",\"distributeur vins du monde\",\"distributeur vins \u00e9trangers\",\"importateur vins du monde\",\"importateur vins \u00e9trangers\",\"vermentino\",\"vin\",\"vin du monde\",\"vin italien\",\"vins du monde\",\"vins \u00e9trangers\"],\"articleSection\":[\"C\u00e9pages\",\"Tous les articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\",\"name\":\"Vermentino : fra\u00eecheur m\u00e9diterran\u00e9enne et subtil, vins du monde\",\"isPartOf\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#website\"},\"datePublished\":\"2024-04-23T16:12:38+00:00\",\"dateModified\":\"2024-11-12T20:19:15+00:00\",\"description\":\"D\u00e9couvrez le Vermentino, c\u00e9page aromatique de M\u00e9diterran\u00e9e. Un vin blanc l\u00e9ger, \u00e9l\u00e9gant, aux notes d'agrumes et de fleurs, vins du monde.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.vinhoselection.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Vermentino, fra\u00eecheur et l\u00e9g\u00e8ret\u00e9 en M\u00e9diterran\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#website\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/\",\"name\":\"Vinho S\u00e9lection - Le Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vinhoselection.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#organization\",\"name\":\"Vinho S\u00e9lection\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png\",\"contentUrl\":\"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png\",\"width\":660,\"height\":86,\"caption\":\"Vinho S\u00e9lection\"},\"image\":{\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d\",\"name\":\"Vinho S\u00e9lection\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g\",\"caption\":\"Vinho S\u00e9lection\"},\"sameAs\":[\"https:\/\/www.vinhoselection.com\/blog\"],\"url\":\"https:\/\/www.vinhoselection.com\/blog\/author\/18vinhoweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vermentino : fra\u00eecheur m\u00e9diterran\u00e9enne et subtil, vins du monde","description":"D\u00e9couvrez le Vermentino, c\u00e9page aromatique de M\u00e9diterran\u00e9e. Un vin blanc l\u00e9ger, \u00e9l\u00e9gant, aux notes d'agrumes et de fleurs, vins du monde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/","og_locale":"fr_FR","og_type":"article","og_title":"Vermentino : fra\u00eecheur m\u00e9diterran\u00e9enne et subtil, vins du monde","og_description":"D\u00e9couvrez le Vermentino, c\u00e9page aromatique de M\u00e9diterran\u00e9e. Un vin blanc l\u00e9ger, \u00e9l\u00e9gant, aux notes d'agrumes et de fleurs, vins du monde.","og_url":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/","og_site_name":"Vinho S\u00e9lection - Le Blog","article_published_time":"2024-04-23T16:12:38+00:00","article_modified_time":"2024-11-12T20:19:15+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2024\/04\/corse.jpg","type":"image\/jpeg"}],"author":"Vinho S\u00e9lection","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Vinho S\u00e9lection","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#article","isPartOf":{"@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/"},"author":{"name":"Vinho S\u00e9lection","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d"},"headline":"Le Vermentino, fra\u00eecheur et l\u00e9g\u00e8ret\u00e9 en M\u00e9diterran\u00e9e","datePublished":"2024-04-23T16:12:38+00:00","dateModified":"2024-11-12T20:19:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/"},"wordCount":728,"commentCount":0,"publisher":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#organization"},"keywords":["d\u00e9gustation","distributeur vins du monde","distributeur vins \u00e9trangers","importateur vins du monde","importateur vins \u00e9trangers","vermentino","vin","vin du monde","vin italien","vins du monde","vins \u00e9trangers"],"articleSection":["C\u00e9pages","Tous les articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/","url":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/","name":"Vermentino : fra\u00eecheur m\u00e9diterran\u00e9enne et subtil, vins du monde","isPartOf":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#website"},"datePublished":"2024-04-23T16:12:38+00:00","dateModified":"2024-11-12T20:19:15+00:00","description":"D\u00e9couvrez le Vermentino, c\u00e9page aromatique de M\u00e9diterran\u00e9e. Un vin blanc l\u00e9ger, \u00e9l\u00e9gant, aux notes d'agrumes et de fleurs, vins du monde.","breadcrumb":{"@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vinhoselection.com\/blog\/2024\/04\/23\/le-vermentino-fraicheur-et-legerete-en-mediterranee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vinhoselection.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Vermentino, fra\u00eecheur et l\u00e9g\u00e8ret\u00e9 en M\u00e9diterran\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.vinhoselection.com\/blog\/#website","url":"https:\/\/www.vinhoselection.com\/blog\/","name":"Vinho S\u00e9lection - Le Blog","description":"","publisher":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vinhoselection.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vinhoselection.com\/blog\/#organization","name":"Vinho S\u00e9lection","url":"https:\/\/www.vinhoselection.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png","contentUrl":"https:\/\/www.vinhoselection.com\/blog\/wp-content\/uploads\/2026\/08\/VinhoSelection_RVB.png","width":660,"height":86,"caption":"Vinho S\u00e9lection"},"image":{"@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/005afe6cfad81e36a1b0f78a3e295f2d","name":"Vinho S\u00e9lection","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vinhoselection.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3972f99bab68245bb83f2630ef07af25?s=96&d=mm&r=g","caption":"Vinho S\u00e9lection"},"sameAs":["https:\/\/www.vinhoselection.com\/blog"],"url":"https:\/\/www.vinhoselection.com\/blog\/author\/18vinhoweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts\/535"}],"collection":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/comments?post=535"}],"version-history":[{"count":1,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts\/535\/revisions"}],"predecessor-version":[{"id":540,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/posts\/535\/revisions\/540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/media\/536"}],"wp:attachment":[{"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/media?parent=535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/categories?post=535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vinhoselection.com\/blog\/wp-json\/wp\/v2\/tags?post=535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}